{"id":1161,"date":"2016-03-25T15:45:49","date_gmt":"2016-03-25T14:45:49","guid":{"rendered":"http:\/\/zycopolis.com\/fr\/marcus\/"},"modified":"2016-05-04T10:46:45","modified_gmt":"2016-05-04T09:46:45","slug":"marcus","status":"publish","type":"post","link":"https:\/\/zycopolis.com\/fr\/marcus\/","title":{"rendered":"Marcus"},"content":{"rendered":"<p>On reconna\u00eet <em>a posteriori<\/em> le g\u00e9nie universel \u00e0 sa capacit\u00e9 d\u2019avoir travers\u00e9 son \u00e9poque en faisant corps avec elle, sans grandes r\u00e9volutions apparentes, sans que jamais la soci\u00e9t\u00e9 dans laquelle il vit ne le per\u00e7oive comme un OVNI. Ce sont des \u00eatres rares. Les artistes surdou\u00e9s, eux, sont nombreux, et l\u2019histoire de la musique regorge de ces talentueux d\u00e9cal\u00e9s, de ces <em>Albatros<\/em> qui, parfois, ne peuvent s\u2019adapter au monde qui les porte. Mais le talent n\u2019est pas le g\u00e9nie. Ce qui distingue le g\u00e9nie de Marcus Miller, c\u2019est sa transparence, sa fa\u00e7on de modifier le monde en profondeur, une sorte de tsunami sans d\u00e9g\u00e2ts collat\u00e9raux.<\/p>\n<p>Patrick Savey nous plonge dans le monde de Marcus, traversant le d\u00e9cor des racines new-yorkaises du l\u00e9gendaire bassiste, suivant sa piste comme les cailloux du Petit Poucet, au gr\u00e9 de ses rencontres artistiques avec les plus grands du jazz, de Larry Graham et Jaco Pastorius \u00e0 David Sanborn, Herbie Hancock, Al Jarreau et Miles Davis, un fantastique voyage musical et visuel.<\/p>\n<p>Remontant l\u2019histoire de ce musicien d\u2019exception \u2013 multi-instrumentiste, compositeur, producteur \u2013 ce film nous fait revivre, \u00e0 travers t\u00e9moignages et extraits de concerts, trois d\u00e9cennies de r\u00e9volution du jazz dans lesquelles Marcus a pris, avec exigence et g\u00e9n\u00e9rosit\u00e9, sa large part. Avec surtout une remarquable humanit\u00e9, une connaissance et une rare appropriation de l\u2019histoire de la musique afro-am\u00e9ricaine, du gospel de son enfance au funk-orchestral de son dernier album\u00a0 \u00ab\u00a0Renaissance\u00a0\u00bb.<\/p>\n<p>Renaissance&#8230; comme le tsunami culturel qui secoua l\u2019Europe. Le temps des g\u00e9nies universels.<\/p>\n<p>Fran\u00e7ois ROBIN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On reconna\u00eet a posteriori le g\u00e9nie universel \u00e0 sa capacit\u00e9 d\u2019avoir travers\u00e9 son \u00e9poque en faisant corps avec elle, sans grandes r\u00e9volutions apparentes, sans que jamais la soci\u00e9t\u00e9 dans laquelle il vit ne le per\u00e7oive comme un OVNI. Ce sont des \u00eatres rares. Les artistes surdou\u00e9s, eux, sont nombreux, et l\u2019histoire de la musique regorge [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[83],"tags":[199,137,478,479,373,136,200,128,27,876,29,877,203,217],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marcus - Zycopolis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zycopolis.com\/fr\/marcus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marcus - Zycopolis\" \/>\n<meta property=\"og:description\" content=\"On reconna\u00eet a posteriori le g\u00e9nie universel \u00e0 sa capacit\u00e9 d\u2019avoir travers\u00e9 son \u00e9poque en faisant corps avec elle, sans grandes r\u00e9volutions apparentes, sans que jamais la soci\u00e9t\u00e9 dans laquelle il vit ne le per\u00e7oive comme un OVNI. Ce sont des \u00eatres rares. Les artistes surdou\u00e9s, eux, sont nombreux, et l\u2019histoire de la musique regorge [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zycopolis.com\/fr\/marcus\/\" \/>\n<meta property=\"og:site_name\" content=\"Zycopolis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zycopolis\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-25T14:45:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-04T09:46:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zycopolis.com\/production-video-concert-documentaire\/Vyoutube-Marcus-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Zycopolis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zycopolis\" \/>\n<meta name=\"twitter:site\" content=\"@zycopolis\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zycopolis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zycopolis.com\/fr\/marcus\/\",\"url\":\"https:\/\/zycopolis.com\/fr\/marcus\/\",\"name\":\"Marcus - Zycopolis\",\"isPartOf\":{\"@id\":\"https:\/\/zycopolis.com\/fr\/#website\"},\"datePublished\":\"2016-03-25T14:45:49+00:00\",\"dateModified\":\"2016-05-04T09:46:45+00:00\",\"author\":{\"@id\":\"https:\/\/zycopolis.com\/fr\/#\/schema\/person\/154bc020743f2e5a2b9290fb68340ae9\"},\"breadcrumb\":{\"@id\":\"https:\/\/zycopolis.com\/fr\/marcus\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zycopolis.com\/fr\/marcus\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zycopolis.com\/fr\/marcus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/zycopolis.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentaires\",\"item\":\"https:\/\/zycopolis.com\/fr\/video-production\/documentaires\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marcus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zycopolis.com\/fr\/#website\",\"url\":\"https:\/\/zycopolis.com\/fr\/\",\"name\":\"Zycopolis\",\"description\":\"Production son &amp; vid\u00e9o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zycopolis.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/zycopolis.com\/fr\/#\/schema\/person\/154bc020743f2e5a2b9290fb68340ae9\",\"name\":\"Zycopolis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/zycopolis.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5cbd7f239dd64a8819e4ecb6f06312c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5cbd7f239dd64a8819e4ecb6f06312c?s=96&d=mm&r=g\",\"caption\":\"Zycopolis\"},\"url\":\"https:\/\/zycopolis.com\/fr\/author\/vincent-zycopolis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marcus - Zycopolis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zycopolis.com\/fr\/marcus\/","og_locale":"fr_FR","og_type":"article","og_title":"Marcus - Zycopolis","og_description":"On reconna\u00eet a posteriori le g\u00e9nie universel \u00e0 sa capacit\u00e9 d\u2019avoir travers\u00e9 son \u00e9poque en faisant corps avec elle, sans grandes r\u00e9volutions apparentes, sans que jamais la soci\u00e9t\u00e9 dans laquelle il vit ne le per\u00e7oive comme un OVNI. Ce sont des \u00eatres rares. Les artistes surdou\u00e9s, eux, sont nombreux, et l\u2019histoire de la musique regorge [&hellip;]","og_url":"https:\/\/zycopolis.com\/fr\/marcus\/","og_site_name":"Zycopolis","article_publisher":"https:\/\/www.facebook.com\/zycopolis","article_published_time":"2016-03-25T14:45:49+00:00","article_modified_time":"2016-05-04T09:46:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/zycopolis.com\/production-video-concert-documentaire\/Vyoutube-Marcus-1.jpg","type":"image\/jpeg"}],"author":"Zycopolis","twitter_card":"summary_large_image","twitter_creator":"@zycopolis","twitter_site":"@zycopolis","twitter_misc":{"\u00c9crit par":"Zycopolis","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zycopolis.com\/fr\/marcus\/","url":"https:\/\/zycopolis.com\/fr\/marcus\/","name":"Marcus - Zycopolis","isPartOf":{"@id":"https:\/\/zycopolis.com\/fr\/#website"},"datePublished":"2016-03-25T14:45:49+00:00","dateModified":"2016-05-04T09:46:45+00:00","author":{"@id":"https:\/\/zycopolis.com\/fr\/#\/schema\/person\/154bc020743f2e5a2b9290fb68340ae9"},"breadcrumb":{"@id":"https:\/\/zycopolis.com\/fr\/marcus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zycopolis.com\/fr\/marcus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zycopolis.com\/fr\/marcus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zycopolis.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Documentaires","item":"https:\/\/zycopolis.com\/fr\/video-production\/documentaires\/"},{"@type":"ListItem","position":3,"name":"Marcus"}]},{"@type":"WebSite","@id":"https:\/\/zycopolis.com\/fr\/#website","url":"https:\/\/zycopolis.com\/fr\/","name":"Zycopolis","description":"Production son &amp; vid\u00e9o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zycopolis.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/zycopolis.com\/fr\/#\/schema\/person\/154bc020743f2e5a2b9290fb68340ae9","name":"Zycopolis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/zycopolis.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5cbd7f239dd64a8819e4ecb6f06312c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5cbd7f239dd64a8819e4ecb6f06312c?s=96&d=mm&r=g","caption":"Zycopolis"},"url":"https:\/\/zycopolis.com\/fr\/author\/vincent-zycopolis\/"}]}},"_links":{"self":[{"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/posts\/1161"}],"collection":[{"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/comments?post=1161"}],"version-history":[{"count":0,"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/posts\/1161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/media\/1145"}],"wp:attachment":[{"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/media?parent=1161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/categories?post=1161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zycopolis.com\/fr\/wp-json\/wp\/v2\/tags?post=1161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}